{"id":6434,"date":"2026-01-31T12:13:52","date_gmt":"2026-01-31T11:13:52","guid":{"rendered":"http:\/\/karinhahnrezensionen.com\/lese24\/?p=6434"},"modified":"2026-05-03T13:47:34","modified_gmt":"2026-05-03T11:47:34","slug":"moa-herngren-schwiegermutter","status":"publish","type":"post","link":"http:\/\/karinhahnrezensionen.com\/lese24\/moa-herngren-schwiegermutter\/","title":{"rendered":"Moa Herngren: Schwiegermutter"},"content":{"rendered":"<p><strong>Moa Herngren: Schwiegermutter, Aus dem Schwedischen von Katharina Martl, Kein &amp; Aber, Z\u00fcrich 2025, 352 Seiten, \u20ac25,00, 978-3-0369-5061-7 <\/strong><\/p>\n<p>\u201e<em>Mir brach kalter Schwei\u00df aus, und ich fr\u00f6stelte. Hier sa\u00df ich, in Dunkelheit und K\u00e4lte. Ich, erfolgreiche Kommunikations- und Leadership-Beraterin, preisgekr\u00f6nt, renommiert und begehrt, wie eine obdachlose Stalkerin.\u201c<\/em><\/p>\n<p>Wird nicht immer behauptet, gerade das Schweigen in Familien f\u00fchrt zu Dissonanzen. Doch in diesem Roman ist die Hauptfigur eine eloquente Kommunikationsexpertin und trotz allem Reden wird \u00c5sa zum Ende hin alles verlieren. Eng ist die Beziehung zwischen der F\u00fcnfundf\u00fcnzigj\u00e4hrigen und ihrem Sohn Andreas, den sie allein gro\u00dfgezogen hat. Der Kindsvater Janne hatte sich zwei Jahre nach Andreas&#8216; Geburt feige von Stockholm Richtung Kopenhagen aus dem Staub gemacht, um mit Helle, die l\u00e4ngst schwanger war, zusammenzuleben. F\u00fcr \u00c5sa bedeutete diese tiefe Dem\u00fctigung einen jahrelangen Groll auf Janne. Da sie nach ihrer postpartalen Depression sowieso schon enorme Schuldgef\u00fchle gegen\u00fcber ihrem Kind plagten, investierte sie nun all ihre Liebe, Kraft und Aufmerksamkeit in ihren Sohn. Andreas jedoch hadert mit seiner Mutter.<\/p>\n<p><em>\u201eAlles blieb an ihr h\u00e4ngen, und sie liebte mich bedingungslos. \u2026 H\u00e4tte sich wenn n\u00f6tig f\u00fcr mich erschie\u00dfen lassen. Und das war also der Dank daf\u00fcr. Es klang vermutlich verr\u00fcckt. Aber ich war es leid, nur f\u00fcr sie zu existieren. Ihretwegen irgendetwas zu machen. Irgendwann erdr\u00fcckte es mich.\u201c<\/em><\/p>\n<p>Dass sie den Kontakt zwischen Vater und Sohn unterbunden hatte, lag sicher auch an den gemeinen Drohungen Jannes, sich um das alleinige Sorgerecht f\u00fcr seinen Sohn zu k\u00fcmmern.<br \/>\nAls sich der neunundzwanzigj\u00e4hrige Andreas nun in Josefin, die Tochter einer langj\u00e4hrigen Freundin von \u00c5sa verliebt, zeigen sich erste Risse in der bisher so harmonischen Mutter \u2013 Sohn \u2013 Beziehung. Auch wenn \u00c5sa in ihrem Gedankenstrom kaum registriert, wie sehr sie ihren erwachsenen Sohn an sich bindet, so versucht dieser sich aus der Symbiose auch mit klarer Unterst\u00fctzung seiner Freundin, insbesondere als er Vater wird, durch eine Therapie zu befreien. Dem allen voraus geht, dass Andreas und seine auch schwierige Freundin ihre Wohnung verlassen mussten und fast ein Dreivierteljahr bei der Mutter, die sich auf die Gesellschaft freute, wohnen. Gibt sich \u00c5sa aus ihrer Sicht M\u00fche, etwas N\u00e4he zu ihrer m\u00f6glichen Schwiegertochter aufzubauen, so zeigt Josefin ihr eher die kalte Schulter und straft sie mit Schweigen und Desinteresse. Als anerkannte Fachfrau f\u00fcr Kommunikation, die jeden Konflikt beheben kann, tritt \u00c5sa dann allerdings unsensibel und \u00fcbergriffig auch in jedes Fettn\u00e4pfchen, dass man sich nur vorstellen kann und \u00fcberschreitet aus Josefins Sicht eindeutig Grenzen.<\/p>\n<p><em>\u201eUnd sie h\u00f6rte nicht auf zu nehmen. Ich war gezwungen, einen hohen Zaun zu errichten, damit sie es begriff. Andreas war jetzt meine Familie. Andreas und Sam. Sie geh\u00f6rten nicht ihr.\u201c <\/em><\/p>\n<p>Haben die Lesenden mit der Ich-Erz\u00e4hlerin \u00c5sa zu Beginn durchaus Verst\u00e4ndnis, da sie nach heftigen Auseinandersetzungen mit Andreas und Josefin keinen Kontakt weder zu ihrem Sohn, noch zu ihrem geliebten Enkel Sam haben darf, so schwindet dieses je mehr sich die Geschichte fortsetzt und kippt wieder in Sympathie um, bis alles in einer Katastrophe endet, weil \u00c5sa erneut die falschen Worte im falschen Moment ausspricht.<br \/>\nWie funktionieren Dynamiken in Kleinfamilien oder wie funktionieren sie nicht? Wer treibt enge Familienmitglieder endg\u00fcltig auseinander, sorgt f\u00fcr Schuldgef\u00fchle, Einsamkeit, Distanz und v\u00f6llige Isolation? Eifers\u00fcchtige, anh\u00e4ngliche Schwiegerm\u00fctter, launische Stieft\u00f6chter oder gar besserwisserische Therapeuten? Was ist verzeihlich und wann muss man wirklich einen Schlussstrich ziehen?<br \/>\nMal aus \u00c5sas Perspektive, dann aber auch aus der Sicht von Andreas und Josefin versinken alle Protagonisten in einem bitteren Wechselbad der Gef\u00fchle und jeder interpretiert die Verhaltensweisen des anderen, ob es nun um Manipulation geht, Schuldgef\u00fchle oder bewusst angelegte Abh\u00e4ngigkeiten, auf ganz unterschiedliche Weise. Moa Herngren vermag es, gleich mit dem ersten Satz die Lesenden in diese fragile, psychologisch genau beobachtete Familiengeschichte hineinzuziehen und bis zum letzten Kapitel, gedanklich wie emotional zu fesseln.<\/p>\n<p>Absolut lesenswert!<\/p>\n<p>Die Besprechung des tiefgr\u00fcndigen wie ebenso klug geschriebenen Romans \u201eScheidung\u201c von Moa Herngren findet Sie ebenfalls in diesem Literaturblog!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moa Herngren: Schwiegermutter, Aus dem Schwedischen von Katharina Martl, Kein &amp; Aber, Z\u00fcrich 2025, 352 Seiten, \u20ac25,00, 978-3-0369-5061-7 \u201eMir brach kalter Schwei\u00df aus, und ich fr\u00f6stelte. Hier sa\u00df ich, in Dunkelheit und K\u00e4lte. Ich, erfolgreiche Kommunikations- und Leadership-Beraterin, preisgekr\u00f6nt, renommiert&#8230; <a class=\"more-link\" href=\"http:\/\/karinhahnrezensionen.com\/lese24\/moa-herngren-schwiegermutter\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":6702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-6434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-belletristik"],"_links":{"self":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/6434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/comments?post=6434"}],"version-history":[{"count":4,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/6434\/revisions"}],"predecessor-version":[{"id":6439,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/6434\/revisions\/6439"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/media\/6702"}],"wp:attachment":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/media?parent=6434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/categories?post=6434"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/tags?post=6434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}