{"id":6049,"date":"2025-07-12T10:09:07","date_gmt":"2025-07-12T08:09:07","guid":{"rendered":"http:\/\/karinhahnrezensionen.com\/lese24\/?p=6049"},"modified":"2025-07-12T10:09:07","modified_gmt":"2025-07-12T08:09:07","slug":"ulf-kvensler-die-insel-einer-kennt-die-ganze-wahrheit","status":"publish","type":"post","link":"http:\/\/karinhahnrezensionen.com\/lese24\/ulf-kvensler-die-insel-einer-kennt-die-ganze-wahrheit\/","title":{"rendered":"Ulf Kvensler: Die Insel, Einer kennt die ganze Wahrheit"},"content":{"rendered":"<p><strong>Ulf Kvensler: Die Insel, Einer kennt die ganze Wahrheit, Aus dem Schwedischen von Sabine Thiele, Penguin Verlag, M\u00fcnchen 2025, 400 Seiten, \u20ac17,00, 978-3-328-11088-0<\/strong><\/p>\n<p><em>\u201eUnd ich erz\u00e4hlte ihr vom meinem Vater, der den Brand f\u00fcr seine Kunst nutzte und gro\u00dfe schreckliche Bilder davon malte. Wie das im Restaurant, nur noch gr\u00f6\u00dfer, noch brutaler, noch schrecklicher, noch sch\u00f6ner. Damit hatte er seinen Durchbruch als K\u00fcnstler, so wurde er bekannt. Mit meinem Trauma machte mein Vater ein Verm\u00f6gen.\u201c <\/em><\/p>\n<p>Als Isak sechs Jahre alt war, verlor er durch einen Brand seine Mutter und seine kleine Schwester. Aufgezogen wurde er von seinen Gro\u00dfeltern m\u00fctterlicherseits, die wenig von seinem angeblich psychisch labilen Vater hielten. Allerdings sucht Isaks Vater nach dem furchtbaren Verlust auch nie den Kontakt zum eigenen Kind und so adoptierten die Gro\u00dfeltern Isak. Heute arbeitet Isak als Altenpfleger f\u00fcr einen h\u00e4uslichen Pflegedienst in Sm\u00e5land und lebt mit seiner Freundin Madde in einer kleinen Mietwohnung. Immer wieder wundert sich Isak, dass Madde an seiner Seite ist. Sie stammt aus einem reichen Elternhaus, wurde aber wohl von ihrer Mutter, zu der sie ein \u00e4u\u00dferst schlechtes Verh\u00e4ltnis hatte, mittellos vor die T\u00fcr gesetzt. Als dann nach Jahren des Schweigens pl\u00f6tzlich Isaks Vater mit ihm sprechen will, sucht der verunsicherte Siebenundzwanzigj\u00e4hrige den Rat bei seinem bodenst\u00e4ndigen Gro\u00dfvater.<br \/>\nDer schwedische Autor Ulf Kvensler erz\u00e4hlt die Handlung seines Romans in R\u00fcckblenden, aber auch auf zwei Zeitebenen. Zum einen erinnert sich Isak an seine schwierige Kindheit und die Lesenden erfahren, wie es ihm und seiner Freundin Madde beim extrem reichen K\u00fcnstlervater auf Gotland ergeht. Als Ich \u2013 Erz\u00e4hler berichtet Isak zum anderen von seiner Zeit in der Untersuchungshaft. Was ihm jedoch nach dem abrupten Ende seines Aufenthaltes auf Gotland vorgeworfen wird, bleibt im Unklaren.<br \/>\nAuf F\u00e5r\u00f6 an der Nordspitze Gotlands wohnt Isaks Vater in einer imposanten Villa. Isak hat sich \u00fcberreden lassen, den T\u00fcrkei-Urlaub gegen den bei seinem Vater, der durch einen diagnostizierten Hirntumor bald sterben wird, einzutauschen. Als Isak mit seinem klapprigen Auto beim charismatischen Vater ankommt und neben zwei teuren Sportwagen parkt, sp\u00fcrt er immer mehr die Wut auf den Mann, der als K\u00fcnstler in London arbeitet und reich geworden ist und f\u00fcr den er, nie wichtig war.<br \/>\nIn verschiedenen Szenen spielt Ulf Kvensler nun durch, wie der manipulative wie willensstarke Vater seinen Sohn und dessen Freundin mit seinem unberechenbaren Wesen und dem m\u00f6glicherweise ausstehenden Millionen &#8211; Erbe ( Da Isak adoptiert wurde, ist er nicht automatisch erbberechtigt. ) unter Druck setzt. Drogen, aber auch Champagner, teure Restaurantbesuche und die Aussicht auf ein sorgenfreies Dasein spielen eine Rolle, wenn der amoralischer Vater, f\u00fcr den Gut und B\u00f6se nichts bedeuten, Mutproben vom Sohn einfordert. Angeblich will er so den verweichlichten Isak vom Einfluss des Gro\u00dfvaters l\u00f6sen und ihm die Freiheit erm\u00f6glichen, die er zum wirklichen Leben ben\u00f6tigt. Stemmt sich Isak mit Zustimmung von Madde zu Beginn gegen die Forderungen des Vaters und droht mit der Abreise, so l\u00e4sst er sich doch zunehmend mehr auf ihn ein. Isak f\u00fchlt sich gefangen in der Zwickm\u00fchle zwischen den schmerzlichen Kr\u00e4nkungen durch den Vater einerseits und der Aussicht auf ein finanziell unabh\u00e4ngiges Leben abseits der Altenpflege andererseits. Getriggert von Gegenst\u00e4nden in der Villa qu\u00e4len Isak aber auch erinnerte Szenen aus seiner Kindheit an den lieblosen Vater und Machtmenschen und der Erkenntnis, dass der traumatische Brand vielleicht kein tragisches Ungl\u00fcck war.<br \/>\nWie jeder gute Thriller endet auch dieser, nachdem es zu einem Eklat zwischen Isak, Madde, dem Vater und dem angereisten Gro\u00dfvater kommt, mit einem unheilvollen Geschehnis, dass Isak ins Gef\u00e4ngnis bringt und die gesamte Figurenkonstellation gnadenlos \u00fcber den Haufen wirft, denn hinter den Hauptfiguren verbirgt sich einiges, was die Lesenden m\u00f6glicherweise ahnen.<\/p>\n<p>Trauer, Tod, Traumata, unsagbarer Reichtum oder ein Dasein im st\u00e4ndigen Dispo \u2013 alle dies vermischt Ulf Kvensler in einer doch sehr konstruierten, doch spannenden, wie temporeichen Handlung, angereichert durch die imposante Landschaft F\u00e5r\u00f6s und dem Traum von einem menschenleeren Strand trotz kaltem Meerwasser.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ulf Kvensler: Die Insel, Einer kennt die ganze Wahrheit, Aus dem Schwedischen von Sabine Thiele, Penguin Verlag, M\u00fcnchen 2025, 400 Seiten, \u20ac17,00, 978-3-328-11088-0 \u201eUnd ich erz\u00e4hlte ihr vom meinem Vater, der den Brand f\u00fcr seine Kunst nutzte und gro\u00dfe schreckliche&#8230; <a class=\"more-link\" href=\"http:\/\/karinhahnrezensionen.com\/lese24\/ulf-kvensler-die-insel-einer-kennt-die-ganze-wahrheit\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":6050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-6049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi"],"_links":{"self":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/6049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/comments?post=6049"}],"version-history":[{"count":2,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/6049\/revisions"}],"predecessor-version":[{"id":6052,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/6049\/revisions\/6052"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/media\/6050"}],"wp:attachment":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/media?parent=6049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/categories?post=6049"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/tags?post=6049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}