{"id":5667,"date":"2024-11-19T09:45:09","date_gmt":"2024-11-19T08:45:09","guid":{"rendered":"http:\/\/karinhahnrezensionen.com\/lese24\/?p=5667"},"modified":"2024-11-19T09:45:09","modified_gmt":"2024-11-19T08:45:09","slug":"alice-elliott-dark-unsere-jahre-auf-fellowship-point","status":"publish","type":"post","link":"http:\/\/karinhahnrezensionen.com\/lese24\/alice-elliott-dark-unsere-jahre-auf-fellowship-point\/","title":{"rendered":"Alice Elliott Dark: Unsere Jahre auf Fellowship Point"},"content":{"rendered":"<p><strong>Alice Elliott Dark: Unsere Jahre auf Fellowship Point, Aus dem amerikanischen Englisch von Margarita Ruppel und Marieke Heimburger, Insel Verlag, Berlin 2024, 733 Seiten, \u20ac28,00, 978-3-458-64414-9 <\/strong><\/p>\n<p><em>\u201eAgnes hatte gro\u00dfen Respekt vor der Intelligenz der anderen Tiere, doch es gab Bereiche, in denen sie sich von Menschen unterschieden, und das Schreiben und Lektorieren von B\u00fcchern geh\u00f6rte dazu.\u201c <\/em><\/p>\n<p>Die \u00fcber achtzigj\u00e4hrige, disziplinierte Schriftstellerin Agnes Lee und Polly Wister, ihre Freundin seit Ewigkeiten, verbringen ihr Leben zu einem Teil in Philadelphia und zum anderen in Maine, in Fellowship Point, einem landschaftlich einmaligen Eiland, das mit wenigen H\u00e4usern und  ausgedehnten Vogelbrutpl\u00e4tzen am Meer liegt.<br \/>\nBeide doch sehr unterschiedliche Frauen, die sich auch mit dem \u00c4lterwerden auseinandersetzen, lieben die Sommerzeit, in der sie sozusagen T\u00fcr an T\u00fcr wohnen. Die eigenwillige Agnes, die nie geheiratet hat und zum Unverst\u00e4ndnis ihrer Umgebung den trockenen britischen Humor liebt, hatte k\u00fcrzlich eine Brustoperation und leidet nun im M\u00e4rz 2000 unter einer Schreibblockade. Bekannt geworden ist sie durch Kinderb\u00fccher, in deren Zentrum das M\u00e4dchen Nan steht. Unter dem Pseudonym Pauline Schulz ver\u00f6ffentlicht Agnes aber auch Belletristik. Die Autorin h\u00fctet allerdings nicht nur ein Geheimnis. Davon werden im Laufe der Handlung ihre Tageb\u00fccher, die in einer Seemannstruhe verborgen sind, berichten.<br \/>\nDie gutm\u00fctige, manchmal naive und auch nerv\u00f6se Polly hingegen ist mit dem ziemlich von sich \u00fcberzeugten Universit\u00e4tsdozenten f\u00fcr Philosophie und Ethik, Dick, verheiratet. Beide haben drei S\u00f6hne und hatten eine Tochter, die jedoch mit neun Jahren verstorben ist. Agnes h\u00e4lt wenig von Dick und hasst es, wenn Polly immer alles erst mal mit ihrem Ehemann besprechen muss. Auch ihr \u00e4ltester Sohn James, er arbeitet in einer Investmentfirma, ist \u00e4hnlich seinem Vater auf seinen eigenen Vorteil bedacht.<br \/>\nNeuerdings besch\u00e4ftigt Agnes und Polly ein ernstes Problem. Ein bekanntes Bautr\u00e4gerunternehmen  will Luxusapartments in der N\u00e4he ihrer H\u00e4user bauen.<br \/>\nImmer aus den Perspektiven von Agnes oder Polly wird von den Geschehnissen zwischen 2000 und 2008 erz\u00e4hlt. Und noch eine Figur berichtet aus ihrer Sicht und das ist die junge Lektorin Maud Silver, die zu gern mit Agnes zusammenarbeiten m\u00f6chte und sie dazu bewegen will, ein Memoir \u00fcber ihre Kindheit und die Entstehungsgeschichte der Nan \u2013 Kinderb\u00fccher zu schreiben. Agnes lehnt dieses Ansinnen vehement ab und doch entsteht zwischen den beiden Frauen im Laufe der Zeit eine enge Beziehung, denn auch Maud muss famili\u00e4r schwierige Entscheidungen treffen.<br \/>\nMit vielen R\u00fcckblicken, auch in die Geschichte der Qu\u00e4ker &#8211; Familie Lee, erz\u00e4hlt Alice Elliott Dark poetisch breit vom Leben der Frauen. Die ruppige und auch st\u00f6rrische Agnes sagt immer, was sie denkt und nimmt nie ein Blatt vor den Mund. Polly ist da eher vorsichtig. Als dann jedoch der G\u00e4rtner Robert Circumstances, angeblich wegen des Stehlens einer Diamantenhalskette, zu zwei Jahren Gef\u00e4ngnis verurteilt wird, ahnen alle, das dies nicht rechtens ist. Dick, und hier zeigt sich seine gute Seite, bleibt mit Robert per Post in Kontakt. Diesen Briefwechsel wird Polly nach Dicks \u00fcberraschend schnellem Tod, weiterf\u00fchren. Auch wenn beide Frauen sich bestens kennen, kommt es doch ausgerechnet nach der tragischen Ereignissen rund um den 11. September 2001 zu einem heftigen Zerw\u00fcrfnis. Agnes braucht Polly mehr als sie zugeben will, aber diese sehnt sich mehr nach ihrer Familie. Durch Dicks Tod, gibt Polly sich nicht auf und widersetzt sich auch der Idee ihrer S\u00f6hne, ein Altenheim aufzusuchen.<\/p>\n<p>Auf gut 731 Seiten schreibt Alice Elliott Dark in ihrem Roman, an dem sie siebzehn Jahre gearbeitet hat, sehr ausufernd, aber sprachlich fesselnd von Lebenswegen amerikanischer Familien, sie erz\u00e4hlt von schwierigen Schreibprozessen, Familienkonflikten, innigster Freundschaft zwischen sehr unterschiedlichen Frauen, Loyalit\u00e4t und vor allem steht im Zentrum dieses volumin\u00f6sen Romans die Liebe zur Natur und die Emanzipation von Frauen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alice Elliott Dark: Unsere Jahre auf Fellowship Point, Aus dem amerikanischen Englisch von Margarita Ruppel und Marieke Heimburger, Insel Verlag, Berlin 2024, 733 Seiten, \u20ac28,00, 978-3-458-64414-9 \u201eAgnes hatte gro\u00dfen Respekt vor der Intelligenz der anderen Tiere, doch es gab Bereiche,&#8230; <a class=\"more-link\" href=\"http:\/\/karinhahnrezensionen.com\/lese24\/alice-elliott-dark-unsere-jahre-auf-fellowship-point\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5667","post","type-post","status-publish","format-standard","hentry","category-belletristik"],"_links":{"self":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/5667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/comments?post=5667"}],"version-history":[{"count":2,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/5667\/revisions"}],"predecessor-version":[{"id":5670,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/posts\/5667\/revisions\/5670"}],"wp:attachment":[{"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/media?parent=5667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/categories?post=5667"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/karinhahnrezensionen.com\/lese24\/wp-json\/wp\/v2\/tags?post=5667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}